{"id":3812,"date":"2020-08-09T17:19:43","date_gmt":"2020-08-09T15:19:43","guid":{"rendered":"https:\/\/hoegy.de\/homepage\/?page_id=3812"},"modified":"2025-01-27T07:44:46","modified_gmt":"2025-01-27T06:44:46","slug":"spanischprofil","status":"publish","type":"page","link":"https:\/\/hoegy.de\/homepage\/schulangebote\/faecher-unterricht\/spanischprofil\/","title":{"rendered":"Spanisch"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span style=\"color: #b60b1e;\"><strong>SPANISCH ALS DRITTE FREMDSPRACHE AM H\u00d6LDERLIN-GYMNASIUM<\/strong><\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Spanisch kann am H\u00f6lderlin-Gymnasium ab der 8. Klasse erlernt werden. Diese Fremdsprache hat am H\u00f6lderlin-Gymnasium inzwischen eine \u00fcber 30-j\u00e4hrige Tradition und wird von vielen Sch\u00fclerinnen und Sch\u00fclern der jeweiligen Jahrg\u00e4nge gew\u00e4hlt.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span style=\"color: #b60b1e;\"><strong>INTERKULTURELLES LERNEN<\/strong><\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Beim Spanischlernen kann man viele L\u00e4nder kennenlernen, in denen Spanisch gesprochen wird (in Spanien, Nord-, Mittel- und S\u00fcdamerika).<\/p>\n<p>Damit es bei der ersten Begegnung mit einer anderen Kultur nicht zu Missverst\u00e4ndnissen kommt, sprechen wir im Spanischunterricht sowohl \u00fcber die Gemeinsamkeiten als auch \u00fcber die Unterschiede verschiedener Kulturen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center us_animate_fade\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"794\" height=\"425\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/SeHabla.png\" class=\"attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/hoegy.de\/homepage\/hgy-media\/SeHabla.png 794w, https:\/\/hoegy.de\/homepage\/hgy-media\/SeHabla-200x107.png 200w, https:\/\/hoegy.de\/homepage\/hgy-media\/SeHabla-600x321.png 600w, https:\/\/hoegy.de\/homepage\/hgy-media\/SeHabla-50x27.png 50w\" data-sizes=\"auto, (max-width: 794px) 100vw, 794px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 794px; --smush-placeholder-aspect-ratio: 794\/425;\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center us_animate_fade\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"856\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle-1024x856.png\" class=\"attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle-1024x856.png 1024w, https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle-200x167.png 200w, https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle-600x502.png 600w, https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle-50x42.png 50w, https:\/\/hoegy.de\/homepage\/hgy-media\/Tabelle.png 1200w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/856;\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span style=\"color: #b60b1e;\"><strong>WAS SPRICHT DAF\u00dcR, SPANISCH IN DER SCHULE ZU LERNEN?<\/strong><\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><ul>\n<li>Jeder 10. Erdbewohner spricht Spanisch.<\/li>\n<li>Spanisch ist die am vierth\u00e4ufigsten gesprochene Sprache der Welt: Z\u00e4hlt man nur die Muttersprachler, so sprechen sogar mehr Menschen Spanisch als Englisch.<\/li>\n<li>Spanisch ist Amtssprache in \u00fcber 22 L\u00e4ndern und Organisationen wie der EU, der UN und Mercosur.<\/li>\n<li>Spanischkenntnisse sind auf dem Arbeitsmarkt gefragt. Der Spanischunterricht vermittelt Kompetenzen, die die Sch\u00fclerinnen und Sch\u00fcler im modernen Europa der offenen Grenzen und weltweit f\u00fcr Kontakte mit der spanischsprachigen Welt ben\u00f6tigen.<\/li>\n<li>Beim Spanischlernen k\u00f6nnen die Sch\u00fcler auf Vorkenntnisse aus Englisch, Franz\u00f6sisch oder Latein zur\u00fcckgreifen.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center us_animate_fade\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-1024x1024.png\" class=\"attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-1024x1024.png 1024w, https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-200x200.png 200w, https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-150x150.png 150w, https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-595x595.png 595w, https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona-50x50.png 50w, https:\/\/hoegy.de\/homepage\/hgy-media\/Barcelona.png 1100w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span style=\"color: #b60b1e;\"><strong>AUSLANDSERFAHRUNG<\/strong><\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Um den Sch\u00fclerinnen und Sch\u00fclern des Spanisch-Profils einen ersten pers\u00f6nlichen Eindruck zu verschaffen, bietet das H\u00f6Gy einen Sch\u00fcleraustausch in Klasse 10 mit einer spanischen Schule in Vilassar de Mar (ein Vorort von Barcelona) an. Die Erfahrungen in spanischen Gastfamilien und mit den spanischsprachigen G\u00e4sten hier in Deutschland sind sehr bereichernd, oft sind daraus langj\u00e4hrige Freundschaften entstanden.<\/p>\n<p>Das H\u00f6lderlin-Gymnasium bekommt auch jedes Jahr Besuch von Sch\u00fclerinnen und Sch\u00fclern aus Chile, die bei H\u00f6Gy-Familien untergebracht werden. Im Gegenzug k\u00f6nnen wir unseren Sch\u00fclerinnen und Sch\u00fclern einen Privataustausch mit Chile vermitteln.<\/p>\n<p>Viele unserer ehemaligen Spanischsch\u00fclerinnen und -sch\u00fcler bewegen sich inzwischen sicher zwischen Feuerland und Alaska und haben zum Teil dank ihrer Spanischkenntnisse interessante berufliche Karrieren eingeschlagen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3><span style=\"color: #b60b1e;\"><strong>SPANISCH IST LEICHT ZU LERNEN<\/strong><\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Rechtschreibung und Aussprache sind sehr einfach. Die Schreibung entspricht im Spanischen ziemlich genau der Aussprache.<\/p>\n<\/div><\/div><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"200\" height=\"200\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien-200x200.png\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien-200x200.png 200w, https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien-150x150.png 150w, https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien-595x595.png 595w, https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien-50x50.png 50w, https:\/\/hoegy.de\/homepage\/hgy-media\/Spanien.png 1000w\" data-sizes=\"auto, (max-width: 200px) 100vw, 200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/200;\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h4><span style=\"color: #b60b1e;\"><strong>KANNST DU DAS SCHON?<\/strong><\/span><\/h4>\n<\/div><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1024\" height=\"917\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas-1024x917.png\" class=\"attachment-large size-large lazyload\" alt=\"\" data-srcset=\"https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas-1024x917.png 1024w, https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas-200x179.png 200w, https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas-600x537.png 600w, https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas-50x45.png 50w, https:\/\/hoegy.de\/homepage\/hgy-media\/new_KannstDuDas.png 1100w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/917;\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_separator]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\"><strong>WIR FREUEN UNS AUF DICH!<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-contacts us_custom_eb849559\"><div class=\"w-contacts-list\"><div class=\"w-contacts-item for_email\"><span class=\"w-contacts-item-value\"><a href=\"mailto:spanisch@hoegy.de\">spanisch@hoegy.de<\/a><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\">\n<\/div><\/div><div class=\"w-tabs style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:inherit\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section\" id=\"o939\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o939\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Weitere Informationen<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o939\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Spanisch als dritte Fremdsprache am H\u00f6lderlin-Gymnasium<\/h2>\n<p>Spanisch kann am H\u00f6lderlin-Gymnasium\u00a0ab der 8. Klasse\u00a0erlernt werden.<\/p>\n<p>Spanisch hat am H\u00f6lderlin-Gymnasium inzwischen eine \u00fcber 15-j\u00e4hrige Tradition und wird in den letzten Jahren von einem deutlichen Gro\u00dfteil der Sch\u00fclerinnen und Sch\u00fcler der jeweiligen Jahrg\u00e4nge gew\u00e4hlt.<\/p>\n<p>Was spricht daf\u00fcr, Spanisch in der Schule zu lernen?<br \/>\nSpanien ist doch nur eines der vielen L\u00e4nder der Europ\u00e4ischen Union und ist nicht einmal direkter Nachbar Deutschlands. Welche Gr\u00fcnde sprechen aber f\u00fcr Spanisch?<\/p>\n<p><u>Die heutige Bedeutung der spanischen Sprache in der Welt<\/u>.<\/p>\n<p><img decoding=\"async\" class=\"alignleft lazyload\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/spanisch1.png\" alt=\"\" width=\"500\" align=\"left\" hspace=\"10\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/354;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Spanisch wird von \u00fcber 350 Millionen Menschen als Muttersprache gesprochen. Damit liegt Spanisch zwar deutlich hinter dem Mandarin-Chinesisch, aber sogar noch vor der Weltsprache Englisch! Hinzu kommen gesch\u00e4tzte 100 Millionen Menschen, die Spanisch als Zweitsprache sprechen.<\/p>\n<p>Nicht zuletzt deshalb ist Spanisch eine der sechs Amtssprachen der UNO; auch in anderen internationalen Organisationen ist Spanisch Amtsssprache (z.B. UNESCO, Welthandelsorganisation, EU).<\/p>\n<p>Das Ministerium f\u00fcr Kultus, Jugend und Sport Baden W\u00fcrttemberg r\u00e4umt dem Spanischen daher ebenfalls eine gro\u00dfe Bedeutung ein:<\/p>\n<p>Spanisch ist (&#8230;) eine der am meisten gesprochenen Weltsprachen. (&#8230;) Der Spanischunterricht vermittelt Kompetenzen, die die Sch\u00fclerinnen und Sch\u00fcler im modernen Europa der offenen Grenzen und weltweit f\u00fcr Kontakte mit <em>Hispanohablantes (<\/em><span style=\"font-style: normal;\">Spanischprachige &#8211; d.Verf.) ben\u00f6tigen. Er erm\u00f6glicht ihnen, ihre fremdsprachlichen F\u00e4higkeiten f\u00fcr Studium und Beruf zu erweitern und so ihre Zukunftschancen zu verbessern\u201c (Bildungsplan 2004).<\/span><\/p>\n<p>In anderen Bundesl\u00e4ndern in Deutschland ist Spanisch inzwischen sogar die zweite Fremdsprache.<\/p>\n<p><img decoding=\"async\" class=\"alignright lazyload\" data-src=\"https:\/\/hoegy.de\/homepage\/hgy-media\/spanisch2.jpg\" alt=\"\" width=\"300\" align=\"right\" hspace=\"10\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/294;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Weltweit ist das Spanisch\u00a0in mehr als 20 L\u00e4ndern der Erde Amtssprache. Dies bezieht sich haupts\u00e4chlich auf den s\u00fcd- und mittelamerikanischen Kontinent, aber auch auf die L\u00e4nder \u00c4quatorialguinea, die Philippinen und nat\u00fcrlich Spanien.<\/p>\n<p>&nbsp;<\/p>\n<p>Dadurch, dass die Vereinigten Staaten von Amerika seit Jahren eine hohe Zahl an Einwanderern aus spanischsprachigen L\u00e4ndern haben, hat sich Spanisch in den USA inzwischen als erste an den Schulen und Universit\u00e4ten unterrichtete Fremdsprache etabliert. Es leben immerhin 30 Millionen Spanischsprachige in den USA. In manchen Gegenden im S\u00fcden der USA (z.B. Kalifornien) hat das Englische gro\u00dfe M\u00fche seine Position zu behaupten &#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wie ist der Spanischunterricht am H\u00f6lderlin-Gymnasium organisiert und was sind seine Inhalte?<\/strong><\/p>\n<p>Folgende Stundenverteilung wartet auf interessierte Sch\u00fclerinnen und Sch\u00fcler:<\/p>\n<table style=\"width: 270px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"99\">\n<p class=\"rtecenter\">Klasse 8<\/p>\n<\/td>\n<td style=\"width: 124px;\">\n<p class=\"rtecenter\">4 Std. \/ Wo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"rtecenter\">Klasse 9<\/p>\n<\/td>\n<td style=\"width: 124px;\" valign=\"top\" width=\"81\">\n<p class=\"rtecenter\">4 Std. \/ Wo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"99\">\n<p class=\"rtecenter\">Klasse 10<\/p>\n<\/td>\n<td style=\"width: 124px;\" valign=\"top\" width=\"81\">\n<p class=\"rtecenter\">4 Std. \/ Wo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"99\">\n<p class=\"rtecenter\">Kursstufe 1<\/p>\n<\/td>\n<td style=\"width: 124px;\" valign=\"top\" width=\"81\">\n<p class=\"rtecenter\">4 Std. \/ Wo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"99\">Kursstufe 2<\/td>\n<td style=\"width: 124px;\" valign=\"top\" width=\"81\">4 Std. \/ Wo<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Selbstverst\u00e4ndlich kann von ihnen nicht erwartet werden, dass sie die Sprache perfekt beherrschen: Die Sch\u00fclerinnen und Sch\u00fcler m\u00fcssen aber die spanische Sprache h\u00f6rend und lesend verstehen und sie sprechen und schreiben k\u00f6nnen, wie im Fach Englisch und Franz\u00f6sisch.<\/p>\n<p>In den ersten zweieinhalb bis drei Schuljahren wird mit Lehrb\u00fcchern (und dazu geh\u00f6rigen Materialien) gearbeitet. Diese werden von den Lehrkr\u00e4ften durch eigene, aktuelle Materialien erg\u00e4nzt. In der sogenannten Lehrbuchphase werden die grammatikalischen Strukturen eingef\u00fchrt, ge\u00fcbt und vertieft. Der Wortschatz wird sukzessive ausgebaut.<\/p>\n<p>Die Lehrb\u00fccher geben ebenso anf\u00e4ngliche Einblicke in das Kulturgut einiger spanischsprachiger L\u00e4nder.<\/p>\n<p>In der Kursstufe werden diese landeskundlichen Inhalte vertieft.<\/p>\n<p>Im Laufe der f\u00fcnf Jahre Spanischunterricht erfahren die Sch\u00fclerinnen und Sch\u00fcler, dass sich die spanische Sprache und Kultur aufgrund historischer Ereignisse \u00fcber die Welt verbreitet hat, die den meisten schon bekannt sind \u2013 das wichtigste Datum der Geschichte war z.B. die Entdeckung Amerikas durch Kolumbus. Viele wissen nicht, dass Kolumbus mit seinen drei Schiffen 1492 von (S\u00fcd-)Spanien unter spanischer Flagge aus startete, nachdem gerade auf der Iberischen Halbinsel die Herrschaft der 700 Jahre lang in Spanien dominierenden Araber mit ihrer sehr weit entwickelten (muslimischen) Kultur beendet worden war. Es folgten mehrere Jahrhunderte der spanischen Kolonisierung des amerikanischen Kontinents (parallel zur eher englischsprachigen Besiedelung des nordamerikanischen Kontinents) und letzlich \u2013 im Zuge der Entwicklung freiheitlicher und aufkl\u00e4rerischer Ideale im gesamten amerikanischen Raum \u2013 die (meist gewaltsame) L\u00f6sung der Menschen von den sie bislang unterjochenden europ\u00e4ischen Kolonialm\u00e4chten. So sind Simon Bol\u00edvar und Jos\u00e9 de San Mart\u00edn f\u00fcr S\u00fcdamerikaner die Befreier, wie es George Washington f\u00fcr die Nordamerikaner ist.<\/p>\n<p>Aktuelle Themen geh\u00f6ren selbstverst\u00e4ndlich entscheidend zu den Inhalten des Spanischunterrichts. Exemplarisch hierf\u00fcr sei die problematische wirtschaftliche, politische und soziale Situation Lateinamerikas genannt. Starke Migrationsstr\u00f6me in die USA sind eine Parallele zu dem Versuch vieler Afrikaner \u00fcber Spanien nach Europa zu gelangen. Wie man auch immer solch einem brisanten Thema gegen\u00fcbersteht, ist es doch wichtig zu wissen, dass noch vor wenigen Jahrzehnten Menschen aus sehr \u00e4hnlichen Gr\u00fcnden aus Europa in Richtung Lateinamerika fl\u00fcchteten.<\/p>\n<p>Die Sch\u00fclerinnen und Sch\u00fcler erhalten durch den Spanischunterricht eine globale Sicht:<\/p>\n<p>Aktuelle wirtschaftliche Entwicklungen in der Welt k\u00f6nnen ohne die Ber\u00fccksichtigung des amerikanischen (also spanisch- und englischsprachigen) Raumes nicht vorgenommen werden. Analog zur politischen und wirtschaftlichen Union der europ\u00e4ischen L\u00e4nder gibt es in Amerika (gemeint ist der gesamte Kontinent) seit einigen Jahren Bestrebungen sich in in \u00fcberregionale B\u00fcndnisse zu begeben. Den meisten d\u00fcrfte die NAFTA (wirtschaftliche Freihandelszone der L\u00e4nder Kanada, Mexiko und USA) oder Mercosur (<em>Mercado Com\u00fan del Sur = Gemeinsamer Markt des S\u00fcdens<\/em><span style=\"font-style: normal;\"> bestehend aus den L\u00e4ndern Argentinien, Brasilien, Paraguay und Uruguay) bekannt sein. <\/span>J\u00fcngeren Datums ist die FTAA\/ALCA (Free Trade Area of the Americas\/Area de Libre Comercio de las Am\u00e9ricas) und ganz aktuell die CSN (Comunidad Sudamericana de Naciones).<\/p>\n<p>Allerdings werden nicht nur wirtschaftlich gewinnbringende\u201c und historische Themen im Unterricht behandelt, sondern auch die sch\u00f6nen\u201c K\u00fcnste, in deren Bereich die spanischsprachige Welt einiges zu bieten hat. Hier ein \u00dcberblick \u00fcber m\u00f6gliche Themen:<\/p>\n<ul>\n<li>lateinamerikanische K\u00fcnstler: der mexikanischen Malerin Frida Kahlo wurde im gleichnamigem Film durch Hollywood j\u00fcngst eine Hommage zuteil<\/li>\n<li>spanische K\u00fcnstler wie Picasso, Mir\u00f3, Dal\u00ed, die die Kunst des 20. Jahrhunderts pr\u00e4gten oder auch Goya und Vel\u00e1zquez des 19. Jahrhunderts<\/li>\n<li>spanische Schriftsteller, wie Cervantes mit seinem <em>Don Quijote<\/em><\/li>\n<li>lateinamerikanische Schriftsteller, wie M\u00e1rquez (Nobelpreistr\u00e4ger mit <em>Hundert Jahre Einsamkeit<\/em><span style=\"font-style: normal;\">) oder Isabel Allende (<\/span><em>Das Geisterhaus<\/em><span style=\"font-style: normal;\">)<\/span><\/li>\n<li>Besonders (aber nat\u00fcrlich nicht nur) bei Jugendlichen erfreut sich spanischsprachige Musik gehobener Beliebtheit, insbesondere in den letzten Jahren hat sie sehr zugelegt: Musiker(innen) wie <em>Shakira, Ricky Martin, Gloria Estefan, Orishas, Juanes<\/em><span style=\"font-style: normal;\"> u.v.m. sind international anerkannt.<\/span><\/li>\n<\/ul>\n<p>Spanisch zu lernen hei\u00dft Kenntnis einer weiteren Sprache und mehr Wissen und Einsichten \u00fcber Kultur und Geschichte eines Gro\u00dfteils der Welt zu erlangen, es hei\u00dft aber auch einen weiteren Schl\u00fcssel f\u00fcr den Zugang zur modernen Arbeitswelt zu erhalten.<\/p>\n<p>Um den Sch\u00fclerinnen und Sch\u00fclern des Spanisch-Profils einen ersten pers\u00f6nlichen Eindruck zu vermitteln, bieten wir die M\u00f6glichkeit, an einer Sprachfahrt nach Roses teilzunehmen. Es k\u00f6nnen auch M\u00f6glichkeiten f\u00fcr einen Privataustausch mit Chile vermittelt werden.<\/p>\n<p>Viele unserer ehemaligen Spanischsch\u00fclerinnen und -sch\u00fcler bewegen sich inzwischen sicher zwischen Feuerland und Alaska und haben z.T. dank ihrer Spanischkenntnisse interessante berufliche Karrieren eingeschlagen.<\/p>\n<hr \/>\n<p><em>gez. Die Fachschaft Spanisch<\/em><\/p>\n<p>Fr. Weber-H\u00e4uptle, Fr. Schurr, Fr. Heusel, H. Weber, H. Sicheneder<\/p>\n<hr \/>\n<h3>Espa\u00f1ol como tercera lengua extranjera en el H\u00f6lderlin-Gymnasium<\/h3>\n<p>En el H\u00f6lderlin-Gymnasium se ense\u00f1a la lengua castellana como asignatura optativa a partir del curso 8\u00b0.<\/p>\n<p>La ense\u00f1anza del espa\u00f1ol en el H\u00f6lderlin-Gymnasium es una asignatura que ya tiene una tradici\u00f3n de m\u00e1s de 15\u00a0a\u00f1os, y a\u00f1o por a\u00f1o cada vez m\u00e1s estudiantes est\u00e1n optando por ella.<\/p>\n<p>Espa\u00f1a s\u00f3lo es uno de los tantos pa\u00edses de la Uni\u00f3n Europea, ni siquiera es vecina directa de Alemania. \u00bfQu\u00e9 ser\u00edan, pues, las razones por estudiar la lengua castellana en un instituto secundario?<\/p>\n<h3>La importancia de la lengua castellana en el mundo hoy en d\u00eda<\/h3>\n<p>El castellano es la lengua materna de m\u00e1s de 350 millones personas. Con ello, el castellano se encuentra en el segunda lugar, lejos, claro est\u00e1, del mandar\u00edn (China), pero por encima incluso de la lengua franca mundial, el ingl\u00e9s. A esto hay que a\u00f1adir unas 100 millones personas que hablan el castellano como segunda lengua.<\/p>\n<p>Por eso, el castellano es uno de los seis idiomas oficiales de la ONU; tambi\u00e9n es idioma oficial en otras organizaciones internacionales (p.e. la Uni\u00f3n Europea, la UNESCO, la Organizaci\u00f3n Mundial del Comercio).<\/p>\n<p>El Ministerio de Cultura, Juventud y Deporte de Baden-Wurtemberg, tambi\u00e9n le concede gran importancia al castellano: \u201cEl espa\u00f1ol es uno de los idiomas m\u00e1s hablados en el mundo. La ense\u00f1anza del espa\u00f1ol proporciona competencias que los alumnos y alumnas necesitan para comunicarse con hispanohablantes en la Europa moderna y en el mundo. Les permite ampliar los conocimientos ling\u00fc\u00edsticos que necesitar\u00e1n en las carreras universitaria y profesional y que mejorar\u00e1n sus oportunidades para el futuro.\u201d (Bildungsplan 2004)<\/p>\n<p>En muchos otros L\u00e4nder de Alemania, el castellano se estudia incluso como lengua extranjera segunda. A nivel mundial el castellano es idioma oficial en m\u00e1s que veinte pa\u00edses, en Am\u00e9rica del sur y central, en los pa\u00edses de Guinea Ecuatorial, las Filipinas y, por supuesto, Espa\u00f1a.<\/p>\n<p>Desde hace varios a\u00f1os, los Estados Unidos experimentan una enorme emigraci\u00f3n de pa\u00edses hispanohablantes, por eso el castellano se ha convertido en la primera lengua extranjera ense\u00f1ada en colegios y universidades. En EEUU viven 30 millones hispanohablantes. Tal es el auge del castellano, que en algunas regiones en el sur de los EEUU (p.e. en California) el ingl\u00e9s tiene muchas dificultades de mantener su liderato. Por eso algunos estados en el suroeste han decidido de declarar expl\u00edcitamente el ingl\u00e9s como idioma nacional en sus respectivas constituciones.<\/p>\n<h3>Los contenidos de la asignatura en el H\u00f6lderlin-Gymnasium<\/h3>\n<p>A los alumnos interesados les espera el siguiente horario:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; border: medium none initial;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 209.5pt; border-width: 0.5pt 0.5pt 0.5pt medium; border-style: solid solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" colspan=\"2\" valign=\"top\" width=\"210\">\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 11pt;\">G8<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 67.85pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"68\">curso 8\u00b0<\/td>\n<td style=\"width: 141.65pt; border-width: 0.5pt 0.5pt 0.5pt medium; border-style: solid solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"142\">4 h a la semana<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 67.85pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"68\">curso 9\u00b0<\/td>\n<td style=\"width: 141.65pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"142\">4 h a la semana<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 67.85pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"68\">curso 10\u00b0<\/td>\n<td style=\"width: 141.65pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"142\">4 h a la semana<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 67.85pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"68\">curso 11\u00b0<\/td>\n<td style=\"width: 141.65pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"142\">4 h a la semana<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 67.85pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"68\">curso 12\u00b0<\/td>\n<td style=\"width: 141.65pt; border-width: medium 0.5pt 0.5pt medium; border-style: none solid solid none; padding: 0cm 5.4pt 0cm 5.4pt;\" valign=\"top\" width=\"142\">4 h a la semana<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Naturalmente no se les puede exigir a los alumnos que lleguen a dominar el idioma perfectamente. Eso s\u00ed, deben entender el idioma leyendo y escuchando y expresarse oralmente y\u00a0por escrito, tal como es el caso en las asignaturas ingl\u00e9s y franc\u00e9s.<\/p>\n<p>En los primeros dos a\u00f1os y medio se trabajar\u00e1 con libros de texto y los materiales de estudio correspondientes (cuadernos de actividades etc.).\u00a0Estos ser\u00e1n complementados por los profesores con propios materiales actuales. En esta primera fase se introducir\u00e1n, se practicar\u00e1n y se profundizar\u00e1n las estructuras gramaticales del idioma. El l\u00e9xico se aumentar\u00e1 progresivamente.<\/p>\n<p>Los libros de texto introducen a la cultura y civilizaci\u00f3n de algunos pa\u00edses hispanohablantes. En la \u201cKursstufe\u201d (curso 11 y 12)\u00a0estos contenidos se profundizar\u00e1n.<\/p>\n<p>A lo largo de los cinco a\u00f1os de ense\u00f1anza del castellano, los alumnos entender\u00e1n que la lengua y la cultura hispana se han distendido por todo el mundo a causa de acontecimientos hist\u00f3ricos, comenzando con un acontecimiento que muchos conocen: el descubrimiento de Am\u00e9rica por Crist\u00f3bal Col\u00f3n. Lo que muchos ignoran es que Col\u00f3n parti\u00f3 con sus tres caravelas bajo la bandera espa\u00f1ola despu\u00e9s de que se hab\u00eda rendido el reino \u00e1rabe de Granada, \u00faltimo residuo de una cultura musulmana altamente desarrollada que hab\u00eda dominado la pen\u00ednsula ib\u00e9rica durante varios siglos.<\/p>\n<p>Al descubrimiento americano siguieron varios siglos de colonizaci\u00f3n hispana (paralela a la colonizaci\u00f3n inglesa del continente norteamericano) y finalmente \u2013 en el marco del desarrollo de los ideales liberales de la Ilustraci\u00f3n en toda Am\u00e9rica \u2013 el desprendimiento generalmente violento de la poblaci\u00f3n americana de las potencias coloniales europeas: Sim\u00f3n Bol\u00edvar y Jos\u00e9 de San Mart\u00edn representan en el sur lo que George Washington es para los EEUU.<\/p>\n<p>Por supuesto el tratamiento de temas actuales tambi\u00e9n son un elemento fundamental de la ense\u00f1anza del espa\u00f1ol. Un ejemplo es la problem\u00e1tica situaci\u00f3n pol\u00edtica, econ\u00f3mica y social de Latinoam\u00e9rica. Las fuertes corrientes migratorias que entran a los EEUU tienen su paralelo en el intento de muchos africanos de encontrar un futuro en Espa\u00f1a. Sea como sea la actitud frente un tema tan explosivo, es importante tener en cuenta que hace poco mucha gente huy\u00f3 de Europa por motivos parecidos en direcci\u00f3n a Latinoam\u00e9rica.<\/p>\n<p>La ense\u00f1anza del espa\u00f1ol les permite a los alumnos adquirir un punto de vista global, que es un aspecto importante si tenemos en cuenta que el desarrollo econ\u00f3mico mundial no se puede observar sin considerar la regi\u00f3n americana (hispanohablante y angloparlante). En analog\u00eda con la uni\u00f3n pol\u00edtica y econ\u00f3mica de los pa\u00edses europeos, ha habido intenciones de establecer alianzas supraregionales en los continentes americanos. Muy conocidos son el MERCOSUR (Mercado Com\u00fan del Sur), el NAFTA (Tratado de Libre Comercio de Am\u00e9rica del Norte entre los pa\u00edses de los EEUU, M\u00e9xico y Canad\u00e1), m\u00e1s joven es la creaci\u00f3n del ALCA (Area de Libre Comercio de las Am\u00e9ricas, ingl: FTAA) y, a\u00fan m\u00e1s reciente la CSN (Comunidad Sudamericana de Naciones).<\/p>\n<p>Pero no se tratan s\u00f3lo los temas \u201c\u00fatiles\u201d econ\u00f3micos e hist\u00f3ricos, sino tambi\u00e9n las expresiones culturales en el arte, la m\u00fasica y la literatura, tan ricas en el mundo hispanoamericano:<\/p>\n<ul style=\"margin-top: 0cm;\">\n<li>Artistas latinoamericanos: Frida Kahlo, la pintora mexicana, fue homenajeado recientemente por Hollywood con una pel\u00edcula que llevaba el nombre de \u201cFrida\u201d como t\u00edtulo.<\/li>\n<li>Artistas espa\u00f1oles como Picasso, Mir\u00f3 o Dal\u00ed que marcaron el arte en el siglo XX o Vel\u00e1zquez y Goya en los siglos XVII y XIX, respectivamente.<\/li>\n<li>Escritores espa\u00f1oles como Cervantes, tan famoso por su <em>Don Quijote.<\/em><\/li>\n<li>Escritores latinoamericanos como Gabriel Garc\u00eda M\u00e1rquez (Premio Nobel con su novela <em>Cien a\u00f1os de soledad<\/em>) o Isabel Allende (<em>La casa de los esp\u00edritus<\/em>)<\/li>\n<li>Muy apreciado por los j\u00f3venes (y mayores, por supuesto) es la m\u00fasica popular en lengua castellana que sobre todo en los \u00faltimos a\u00f1os ha tenido un auge ins\u00f3lito. Cantantes como Shakira, Ricky Martin, Gloria Estefan, Orishas, Juanes etc. son artistas reconocidos en todo el mundo.<\/li>\n<\/ul>\n<p>Aprender castellano no s\u00f3lo significa obtener el conocimiento de una lengua m\u00e1s, o el conocimiento y la comprensi\u00f3n de la cultura e historia de una gran parte del mundo, tambi\u00e9n significa recibir una llave m\u00e1s que permite el acceso al mundo laboral actual.<\/p>\n<h3>Intercambios<\/h3>\n<p>Para proporcionarles una primera impresi\u00f3n personal del mundo hispano, les ofrecemos a los alumnos de espa\u00f1ol la posibilidad de participar en un viaje de estudios a Roses. Tambi\u00e9n se pueden gestionar intercambios privados con Chile.<\/p>\n<p>Muchos de nuestros antiguos alumnos de espa\u00f1ol se mueven seguros entre Tierra del Fuego y Alaska, y lograron acceder a carreras profesionales interesantes.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"SPANISCH ALS DRITTE FREMDSPRACHE AM H\u00d6LDERLIN-GYMNASIUM Spanisch kann am H\u00f6lderlin-Gymnasium ab der 8. Klasse erlernt werden. Diese Fremdsprache hat am H\u00f6lderlin-Gymnasium inzwischen eine \u00fcber 30-j\u00e4hrige Tradition und wird von vielen Sch\u00fclerinnen und Sch\u00fclern der jeweiligen Jahrg\u00e4nge gew\u00e4hlt. INTERKULTURELLES LERNEN Beim Spanischlernen kann man viele L\u00e4nder kennenlernen, in denen Spanisch gesprochen wird (in Spanien, Nord-, Mittel-...","protected":false},"author":2,"featured_media":3819,"parent":218,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3812","page","type-page","status-publish","has-post-thumbnail","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:17:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/pages\/3812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/comments?post=3812"}],"version-history":[{"count":24,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/pages\/3812\/revisions"}],"predecessor-version":[{"id":13234,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/pages\/3812\/revisions\/13234"}],"up":[{"embeddable":true,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/pages\/218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"https:\/\/hoegy.de\/homepage\/wp-json\/wp\/v2\/media?parent=3812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}